{"id":5022,"count":1,"description":"","link":"https:\/\/zurzeit.at\/index.php\/tag\/theater-in-der-josefstadt\/","name":"Theater in der Josefstadt","slug":"theater-in-der-josefstadt","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Theater in der Josefstadt Archive - ZurZeit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zurzeit.at\/index.php\/tag\/theater-in-der-josefstadt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Theater in der Josefstadt Archive - ZurZeit\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zurzeit.at\/index.php\/tag\/theater-in-der-josefstadt\/\" \/>\n<meta property=\"og:site_name\" content=\"ZurZeit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zurzeit.at\\\/index.php\\\/tag\\\/theater-in-der-josefstadt\\\/\",\"url\":\"https:\\\/\\\/zurzeit.at\\\/index.php\\\/tag\\\/theater-in-der-josefstadt\\\/\",\"name\":\"Theater in der Josefstadt Archive - ZurZeit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zurzeit.at\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zurzeit.at\\\/index.php\\\/tag\\\/theater-in-der-josefstadt\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zurzeit.at\\\/index.php\\\/tag\\\/theater-in-der-josefstadt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zurzeit.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Theater in der Josefstadt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zurzeit.at\\\/#website\",\"url\":\"https:\\\/\\\/zurzeit.at\\\/\",\"name\":\"ZurZeit\",\"description\":\"Internetseite des Wochenmagazins ZurZeit\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zurzeit.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Theater in der Josefstadt Archive - ZurZeit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zurzeit.at\/index.php\/tag\/theater-in-der-josefstadt\/","og_locale":"de_DE","og_type":"article","og_title":"Theater in der Josefstadt Archive - ZurZeit","og_url":"https:\/\/zurzeit.at\/index.php\/tag\/theater-in-der-josefstadt\/","og_site_name":"ZurZeit","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zurzeit.at\/index.php\/tag\/theater-in-der-josefstadt\/","url":"https:\/\/zurzeit.at\/index.php\/tag\/theater-in-der-josefstadt\/","name":"Theater in der Josefstadt Archive - ZurZeit","isPartOf":{"@id":"https:\/\/zurzeit.at\/#website"},"breadcrumb":{"@id":"https:\/\/zurzeit.at\/index.php\/tag\/theater-in-der-josefstadt\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/zurzeit.at\/index.php\/tag\/theater-in-der-josefstadt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zurzeit.at\/"},{"@type":"ListItem","position":2,"name":"Theater in der Josefstadt"}]},{"@type":"WebSite","@id":"https:\/\/zurzeit.at\/#website","url":"https:\/\/zurzeit.at\/","name":"ZurZeit","description":"Internetseite des Wochenmagazins ZurZeit","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zurzeit.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/zurzeit.at\/index.php\/wp-json\/wp\/v2\/tags\/5022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zurzeit.at\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/zurzeit.at\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/zurzeit.at\/index.php\/wp-json\/wp\/v2\/posts?tags=5022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}